{"id":52142,"date":"2023-02-28T19:34:23","date_gmt":"2023-02-28T19:34:23","guid":{"rendered":"https:\/\/funtechinnovation.com\/innex\/visualizer-dc500\/"},"modified":"2026-01-13T15:18:39","modified_gmt":"2026-01-13T07:18:39","slug":"visualizer-dc500","status":"publish","type":"page","link":"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/","title":{"rendered":"Innex Visualizer DC500"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"52142\" class=\"elementor elementor-52142\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-357eef2 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"357eef2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9594b96\" data-id=\"9594b96\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27a6a93 elementor-widget elementor-widget-spacer\" data-id=\"27a6a93\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-236114b elementor-widget elementor-widget-heading\" data-id=\"236114b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dokumentenkamera<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f6c9d5 elementor-widget elementor-widget-image\" data-id=\"4f6c9d5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1128\" height=\"135\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/02\/innex-DC500-logo.png\" class=\"attachment-full size-full wp-image-37144\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/02\/innex-DC500-logo.png 1128w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/02\/innex-DC500-logo-300x36.png 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/02\/innex-DC500-logo-1024x123.png 1024w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/02\/innex-DC500-logo-768x92.png 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/02\/innex-DC500-logo-650x78.png 650w\" sizes=\"auto, (max-width: 1128px) 100vw, 1128px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fb9514 elementor-widget elementor-widget-text-editor\" data-id=\"2fb9514\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>4K-Doc-Cam\/Webcam mit Mikrofon mit Ger\u00e4uschunterdr\u00fcckung<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-a8ceb26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8ceb26\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1004c3e\" data-id=\"1004c3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a9ecbd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5a9ecbd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/Innex_DC500_flyer-0511.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Datenblatt<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9bf125c\" data-id=\"9bf125c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84831b6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"84831b6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/funtechinnovation.com\/de\/software\/ideao-visualcam\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Ideao VisualCam (Windows\/Mac)<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-318305e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"318305e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/funtechinnovation.com\/de\/software\/ideaocam\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">IdeaoCam (Chrome-Erweiterung)<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b975904 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b975904\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/drive.google.com\/drive\/folders\/14zUNRYoowNEYXSm0G2f4G9YzgEb20Ovc\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Ideao VisualCam Lite (Android)<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2144701 elementor-widget elementor-widget-spacer\" data-id=\"2144701\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d6af33e\" data-id=\"d6af33e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2f630c9 elementor-section-height-min-height elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"2f630c9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0f5723d\" data-id=\"0f5723d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-f5ff779 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"f5ff779\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-703bcb1\" data-id=\"703bcb1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b433f26 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b433f26\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/camera.png\" class=\"attachment-full size-full wp-image-17724\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/camera.png 120w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/camera-100x100.png 100w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">13-MP-Kamera<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-832282b\" data-id=\"832282b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b371b58 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b371b58\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/microphone.png\" class=\"attachment-full size-full wp-image-17730\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/microphone.png 120w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/microphone-100x100.png 100w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Mikrofon mit Ger\u00e4uschunterdr\u00fcckung<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a1591cc\" data-id=\"a1591cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d0b813 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8d0b813\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/03\/smart-focus.png\" class=\"attachment-full size-full wp-image-37596\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/03\/smart-focus.png 120w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/03\/smart-focus-100x100.png 100w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Intelligenter Fokus<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8376a55\" data-id=\"8376a55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e68a04 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"2e68a04\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/03\/auto-rotate.png\" class=\"attachment-full size-full wp-image-37591\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/03\/auto-rotate.png 120w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/03\/auto-rotate-100x100.png 100w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">G-Sensor automatisch drehen<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-f1020cb elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"f1020cb\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-642364b\" data-id=\"642364b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-219f819 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"219f819\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/light-bulb.png\" class=\"attachment-full size-full wp-image-17729\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/light-bulb.png 120w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/light-bulb-100x100.png 100w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">LED-Licht<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3ccd81e\" data-id=\"3ccd81e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc35ef3 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bc35ef3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/05\/plugplay.png\" class=\"attachment-full size-full wp-image-19373\" alt=\"icon plug&amp;play\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Plug & Play<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a576952\" data-id=\"a576952\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9244210 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9244210\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/05\/pocket-sized.png\" class=\"attachment-full size-full wp-image-19374\" alt=\"icon pocket-sized compact design\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Kompaktes Design<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e37ef6b\" data-id=\"e37ef6b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b451ff9 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b451ff9\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/05\/software.png\" class=\"attachment-full size-full wp-image-19802\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Interaktive Software<\/h3><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-941b65c\" data-id=\"941b65c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bafb90e elementor-widget elementor-widget-image\" data-id=\"bafb90e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1018\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/dc500-mainR.png\" class=\"attachment-large size-large wp-image-40495\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/dc500-mainR.png 1000w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/dc500-mainR-295x300.png 295w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/dc500-mainR-768x782.png 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/dc500-mainR-650x662.png 650w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0f39762 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"0f39762\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59a3105 elementor-invisible\" data-id=\"59a3105\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-442068f elementor-widget elementor-widget-spacer\" data-id=\"442068f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4a304f elementor-widget elementor-widget-heading\" data-id=\"c4a304f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Perfektes Detail. Perfekte Fernkommunikation.<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63753df elementor-widget elementor-widget-text-editor\" data-id=\"63753df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Pr\u00e4sentieren und unterrichten Sie wie ein Profi mit der vielseitigen 4K-Dokumentenkamera Innex DC500.<\/p><p>Es ist ein ultimatives Werkzeug f\u00fcr Lehrer und Sch\u00fcler, die eine hochwertige Kamera f\u00fcr die Pr\u00e4sentation von Dokumenten, Hausaufgaben und anderen Materialien ben\u00f6tigen. Einfaches Plug-and-Play und dank des faltbaren, kompakten Designs leicht zu verstauen. Innex DC500 ist die perfekte Erg\u00e4nzung f\u00fcr jedes Klassenzimmer, jede Lernumgebung oder sogar f\u00fcr B\u00fcrokonferenzen!<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6a2a64 elementor-hidden-phone elementor-widget elementor-widget-spacer\" data-id=\"e6a2a64\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-ef6594f elementor-section-height-min-height elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"ef6594f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c1c5046 elementor-invisible\" data-id=\"c1c5046\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-319622c elementor-widget elementor-widget-heading\" data-id=\"319622c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">KI-gest\u00fctzte Ger\u00e4uschunterdr\u00fcckung<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e10533 elementor-widget elementor-widget-heading\" data-id=\"9e10533\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Klare Kommunikation in jeder Umgebung<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-777da81 elementor-widget elementor-widget-text-editor\" data-id=\"777da81\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>EingebautMikrofon mit Ger\u00e4uschunterdr\u00fcckungDadurch wird sichergestellt, dass Ihre Stimme laut und deutlich zu h\u00f6ren ist, egal ob Sie von zu Hause aus unterrichten oder aus der Ferne lernen. Befreien Sie sich von st\u00f6renden Hintergrundger\u00e4uschen und konzentrieren Sie sich auf Ihre Inhalte!<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c96139e\" data-id=\"c96139e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd8a9b1 elementor-widget elementor-widget-image\" data-id=\"bd8a9b1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"652\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-pic-3-1024x652.jpg\" class=\"attachment-large size-large wp-image-38757\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-pic-3-1024x652.jpg 1024w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-pic-3-300x191.jpg 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-pic-3-768x489.jpg 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-pic-3-1536x978.jpg 1536w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-pic-3-650x414.jpg 650w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-pic-3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65fcf87 elementor-widget elementor-widget-spacer\" data-id=\"65fcf87\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4651ee9 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4651ee9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f870048\" data-id=\"f870048\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53f981d elementor-widget elementor-widget-image\" data-id=\"53f981d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/ideao-visual-cam_layout-1-1024x576.jpg\" class=\"attachment-large size-large wp-image-38887\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/ideao-visual-cam_layout-1-1024x576.jpg 1024w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/ideao-visual-cam_layout-1-300x169.jpg 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/ideao-visual-cam_layout-1-768x432.jpg 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/ideao-visual-cam_layout-1-1536x864.jpg 1536w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/ideao-visual-cam_layout-1-800x450.jpg 800w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/ideao-visual-cam_layout-1-650x366.jpg 650w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/ideao-visual-cam_layout-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c08570d elementor-widget elementor-widget-spacer\" data-id=\"c08570d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f9c5a2d elementor-invisible\" data-id=\"f9c5a2d\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7ece79 elementor-widget elementor-widget-heading\" data-id=\"f7ece79\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Erstaunliche Videoqualit\u00e4t<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c208b59 elementor-widget elementor-widget-text-editor\" data-id=\"c208b59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Mit seiner 4K-Aufl\u00f6sung erfasst der Innex DC500 jedes Detail Ihrer Materialien mit atemberaubender Klarheit und Pr\u00e4zision. Ob Sie eine komplexe mathematische Gleichung pr\u00e4sentieren oder ein heikles Kunstprojekt vorf\u00fchren, diese Kamera stellt sicher, dass Ihr Publikum alles klar sehen kann!<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e00f29a elementor-section-height-min-height elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"e00f29a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b748780 elementor-invisible\" data-id=\"b748780\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edb0b86 elementor-widget elementor-widget-heading\" data-id=\"edb0b86\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Automatische Bilddrehung<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dcb0a5 elementor-widget elementor-widget-text-editor\" data-id=\"3dcb0a5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Wechseln Sie mit der Innex DC500 ganz einfach von einer Overhead-Dokumentenkamera zu einer nach vorne gerichteten Webcam. Der eingebauteG-SensorPasst das Bild automatisch an die richtige Ausrichtung an und wechselt nahtlos zwischen den Modi \u201eDoc Cam\u201c und \u201eWebcam\u201c. Perfekt f\u00fcr virtuelles Lehren und Lernen.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a984bf\" data-id=\"3a984bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6a9a24 elementor-widget elementor-widget-image\" data-id=\"a6a9a24\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"656\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/dc500-webcam-mode-1024x656.jpg\" class=\"attachment-large size-large wp-image-38762\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/dc500-webcam-mode-1024x656.jpg 1024w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/dc500-webcam-mode-300x192.jpg 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/dc500-webcam-mode-768x492.jpg 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/dc500-webcam-mode-650x416.jpg 650w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/dc500-webcam-mode.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-247a8b7 elementor-widget elementor-widget-spacer\" data-id=\"247a8b7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-ee8cf93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee8cf93\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-915d074\" data-id=\"915d074\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebcf907 elementor-widget elementor-widget-heading\" data-id=\"ebcf907\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Dual-Fokus-Modi f\u00fcr vielseitigen Einsatz<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-fe7dddf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fe7dddf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cbd4ef2\" data-id=\"cbd4ef2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc949c1 elementor-widget elementor-widget-image\" data-id=\"dc949c1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"652\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-webcam-1024x652.jpg\" class=\"attachment-large size-large wp-image-38870\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-webcam-1024x652.jpg 1024w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-webcam-300x191.jpg 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-webcam-768x489.jpg 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-webcam-1536x978.jpg 1536w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-webcam-650x414.jpg 650w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-webcam.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c22671 elementor-widget elementor-widget-heading\" data-id=\"9c22671\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Autofokus Ein<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be95a81 elementor-widget elementor-widget-text-editor\" data-id=\"be95a81\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Wenn der Autofokus eingeschaltet ist, passt die Innex DC500 ihren Fokus st\u00e4ndig an, wenn sie erkennt, dass sich das Aufnahmeobjekt bewegt. Dieser Modus stellt sicher, dass das Video scharf und scharf bleibt, auch wenn Sie sich bewegen, und eignet sich daher perfekt f\u00fcr die Verwendung als Webcam oder zum Teilen dynamischer Inhalte.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-532270b\" data-id=\"532270b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8e2863 elementor-widget elementor-widget-image\" data-id=\"b8e2863\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"652\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-doccam-1024x652.jpg\" class=\"attachment-large size-large wp-image-38875\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-doccam-1024x652.jpg 1024w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-doccam-300x191.jpg 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-doccam-768x489.jpg 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-doccam-1536x978.jpg 1536w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-doccam-650x414.jpg 650w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/DC500-s-doccam.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1cfbe1 elementor-widget elementor-widget-heading\" data-id=\"e1cfbe1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Autofokus aus (einmaliger Fokus)<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e844fd6 elementor-widget elementor-widget-text-editor\" data-id=\"e844fd6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Wenn der Autofokus ausgeschaltet ist, passt die Innex DC500 ihren Fokus erst wieder an, wenn Sie die Fokustaste dr\u00fccken, um den Autofokus auszul\u00f6sen. Dieser Modus hilft dabei, das Video ruhig zu halten und verhindert, dass es hin und her springt, was ihn ideal f\u00fcr die Aufnahme flacher Objekte wie Dokumente und Gem\u00e4lde macht.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-d51a224 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d51a224\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e84bb03\" data-id=\"e84bb03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5c2a73 elementor-widget elementor-widget-spacer\" data-id=\"a5c2a73\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e15eb15 elementor-widget elementor-widget-heading\" data-id=\"e15eb15\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Entdecken Sie Innex DC500<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0366ca elementor-widget elementor-widget-oew-hotspots\" data-id=\"a0366ca\" data-element_type=\"widget\" data-settings=\"{&quot;fade_in_time&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:200,&quot;sizes&quot;:[]},&quot;fade_out_time&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]}}\" data-widget_type=\"oew-hotspots.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div class=\"oew-hotspots-wrap\">\r\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"627\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hwR4-1024x627.png\" class=\"attachment-large size-large wp-image-40490\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hwR4-1024x627.png 1024w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hwR4-300x184.png 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hwR4-768x470.png 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hwR4-650x398.png 650w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hwR4.png 1100w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\r\n\t\t\t\t\t\t\t<div class=\"oew-hotspot-wrap\">\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"oew-hotspot-inner elementor-repeater-item-4918967 oew-hotspot-tooltip oew-tooltip-s\" aria-label=\"&lt;p&gt;Autofokus \/ 180-Grad-Rotationsausl\u00f6ser&lt;\/p&gt;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"oew-hotspot-inner elementor-repeater-item-5f27ef7 oew-hotspot-tooltip oew-tooltip-s\" aria-label=\"&lt;p&gt;3-stufiges LED-Licht&lt;\/p&gt;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"oew-hotspot-inner elementor-repeater-item-98555ee oew-hotspot-tooltip oew-tooltip-s\" aria-label=\"&lt;p&gt;Autofokus ein- und ausschalten&lt;\/p&gt;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"oew-hotspot-inner elementor-repeater-item-e0d4f35 oew-hotspot-tooltip oew-tooltip-s\" aria-label=\"&lt;p&gt;Automatische Drehung ein- und ausschalten&lt;\/p&gt;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"oew-hotspot-inner elementor-repeater-item-cadbf4d oew-hotspot-tooltip oew-tooltip-s\" aria-label=\"&lt;p&gt;AI-Ger\u00e4uschunterdr\u00fcckung ein- und ausschalten&lt;\/p&gt;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"oew-hotspot-inner elementor-repeater-item-c923730 oew-hotspot-tooltip oew-tooltip-s\" aria-label=\"&lt;p&gt;Einstellbare Dichtheit des Scharniers&lt;\/p&gt;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"oew-hotspot-inner elementor-repeater-item-3e9aa2c oew-hotspot-tooltip oew-tooltip-s\" aria-label=\"&lt;p&gt;Zusammenklappbares, kompaktes Design&lt;\/p&gt;\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-351a8ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"351a8ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6c4b5b7\" data-id=\"6c4b5b7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-567760a elementor-widget elementor-widget-image\" data-id=\"567760a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"359\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/Dc500-hw-button.png\" class=\"attachment-large size-large wp-image-38767\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/Dc500-hw-button.png 800w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/Dc500-hw-button-300x135.png 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/Dc500-hw-button-768x345.png 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/Dc500-hw-button-650x292.png 650w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d87ae6 elementor-widget elementor-widget-heading\" data-id=\"6d87ae6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Autofokus und LED-Licht<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d065c8f elementor-widget elementor-widget-text-editor\" data-id=\"d065c8f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Autofokus: Manuelles Ausl\u00f6sen des Autofokus durch leichtes Dr\u00fccken oder 180\u00b0-Drehung durch langes Dr\u00fccken.\u00a0<\/p><p>LED : 3-stufiges LED-Licht.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7d8123a\" data-id=\"7d8123a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab7571d elementor-widget elementor-widget-image\" data-id=\"ab7571d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"359\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-afR3.png\" class=\"attachment-large size-large wp-image-40470\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-afR3.png 800w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-afR3-300x135.png 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-afR3-768x345.png 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-afR3-650x292.png 650w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3712e30 elementor-widget elementor-widget-heading\" data-id=\"3712e30\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Autofokus<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d42c1a9 elementor-widget elementor-widget-text-editor\" data-id=\"d42c1a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong><span style=\"color: #ff6600;\">Ein<\/span><\/strong>: Konstanter Autofokus, geeignet f\u00fcr Webcam-Modus.<\/p><p><strong><span style=\"color: #ff6600;\">Aus<\/span><\/strong>: Einmalige Fokussierung. L\u00f6sen Sie den Fokus manuell aus, indem Sie die +-Taste dr\u00fccken. Geeignet f\u00fcr den Dokumentenkameramodus.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-31f5dfe\" data-id=\"31f5dfe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-148b308 elementor-widget elementor-widget-image\" data-id=\"148b308\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"359\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-rotate-noiseR2.png\" class=\"attachment-large size-large wp-image-40459\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-rotate-noiseR2.png 800w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-rotate-noiseR2-300x135.png 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-rotate-noiseR2-768x345.png 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/06\/Dc500-hw-rotate-noiseR2-650x292.png 650w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7d51f5 elementor-widget elementor-widget-heading\" data-id=\"a7d51f5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">KI-Ger\u00e4uschunterdr\u00fcckung<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b2965d elementor-widget elementor-widget-text-editor\" data-id=\"4b2965d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong><span style=\"color: #ff6600;\">Ein<\/span><\/strong>: Reduziert Hintergrundger\u00e4usche und erfasst nur die n\u00e4chstgelegene Stimme.<\/p><p><strong><span style=\"color: #ff6600;\">Aus<\/span><\/strong>: Erfasst alles.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a175a11 elementor-widget elementor-widget-spacer\" data-id=\"a175a11\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4b5b40a elementor-section-height-min-height elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4b5b40a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6626dd3 elementor-invisible\" data-id=\"6626dd3\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e70f872 elementor-widget elementor-widget-heading\" data-id=\"e70f872\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Interaktive Ideao-Software<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8677a80 elementor-widget elementor-widget-text-editor\" data-id=\"8677a80\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Nutzen Sie die leistungsstarke Ideao-Software, um mehr zu erreichen: Split-Modus-Vergleich, Bildspiegelung und Kommentieren des Inhalts.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf226d1 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"cf226d1\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/funtechinnovation.com\/de\/software\/ideao-visualcam\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Laden Sie Ideao VisualCam herunter (Windows \/ Mac)<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8617ef elementor-align-left elementor-widget elementor-widget-button\" data-id=\"b8617ef\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/funtechinnovation.com\/de\/software\/ideaocam\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-down\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">IdeaoCam (Chrome-Erweiterung) herunterladen<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f18ff16\" data-id=\"f18ff16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c682a8 elementor-widget elementor-widget-spacer\" data-id=\"8c682a8\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7741abd elementor-widget elementor-widget-image\" data-id=\"7741abd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/01\/ideaovisualcam4-1024x576.jpg\" class=\"attachment-large size-large wp-image-27394\" alt=\"\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/01\/ideaovisualcam4-1024x576.jpg 1024w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/01\/ideaovisualcam4-300x169.jpg 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/01\/ideaovisualcam4-768x432.jpg 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/01\/ideaovisualcam4-1536x864.jpg 1536w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/01\/ideaovisualcam4-650x366.jpg 650w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/01\/ideaovisualcam4.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-126b221 elementor-widget elementor-widget-spacer\" data-id=\"126b221\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7067c59 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7067c59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04f0f82 elementor-invisible\" data-id=\"04f0f82\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b64b39 elementor-widget elementor-widget-heading\" data-id=\"7b64b39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kompatibel mit Online-Kommunikationssoftware<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e40c2f elementor-widget elementor-widget-spacer\" data-id=\"5e40c2f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5894056 elementor-widget elementor-widget-image\" data-id=\"5894056\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"73\" src=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/software_icon_1--1024x73.png\" class=\"attachment-large size-large wp-image-18436\" alt=\"video conferencing icons\" srcset=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/software_icon_1--1024x73.png 1024w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/software_icon_1--300x22.png 300w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/software_icon_1--768x55.png 768w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/software_icon_1--1536x110.png 1536w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/software_icon_1--2048x147.png 2048w, https:\/\/funtechinnovation.com\/wp-content\/uploads\/2021\/04\/software_icon_1--650x47.png 650w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-cd4d134 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cd4d134\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78f2756\" data-id=\"78f2756\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c19ff30 oew-flip-box-direction-up oew-flip-box-effect-flip elementor-widget elementor-widget-oew-flip-box\" data-id=\"c19ff30\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"oew-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div class=\"oew-flip-box\">\r\n\r\n\t\t\t<div class=\"oew-flip-box-layer oew-flip-box-front\">\r\n\t\t\t\t<div class=\"oew-flip-box-layer-overlay\">\r\n\t\t\t\t\t<div class=\"oew-flip-box-layer-inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-wrap elementor-view-default\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t\t<div class=\"oew-flip-box-layer oew-flip-box-back\">\r\n\t\t\t\t<div class=\"oew-flip-box-layer-overlay\">\r\n\t\t\t\t\t<div class=\"oew-flip-box-layer-inner\">\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\r\n\t\t<\/div>\r\n\r\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d442222 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d442222\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Gro\u00dfe Portabilit\u00e4t<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63c2c0f elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"63c2c0f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Nehmen Sie es \u00fcberallhin mit, egal ob Sie von Klassenzimmer zu Klassenzimmer oder von einem Ort zum anderen ziehen. Der Innex DC500 verf\u00fcgt \u00fcber ein faltbares Scharnierdesign, das ihn unglaublich tragbar und einfach zu verstauen macht!<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c306d7 elementor-widget elementor-widget-spacer\" data-id=\"0c306d7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6c75314 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c75314\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-843be94\" data-id=\"843be94\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f08f13 elementor-widget elementor-widget-spacer\" data-id=\"7f08f13\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fca195 elementor-widget elementor-widget-heading\" data-id=\"8fca195\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">SPEZIFIKATIONEN<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-78c083a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78c083a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-687fcf7\" data-id=\"687fcf7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71bbdc4 elementor-widget elementor-widget-toggle\" data-id=\"71bbdc4\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1191\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1191\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Kamera<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1191\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1191\"><p>Max. Ausgabeaufl\u00f6sung und FPS:<br \/>4160&#215;3120 <br \/>(mit Windows Version VisualCam)<br \/>3840\u00d72880 bei 15 Bildern pro Sekunde (zur Aufnahme von A3-Bildern)<br \/>3840\u00d72160 bei 30 Bildern pro Sekunde<br \/>1920\u00d71080 bei 60 Bildern pro Sekunde<\/p><p>Video-Kompression:MJPG\/YUY2<\/p><p>Fokus:Autofokus\/Einmaliger Fokus<\/p><p>Aufnahme bei schwachem Licht:Unterst\u00fctzung<\/p><p>Max. Schie\u00dfplatz:440 x 330 mm \/ 17,3 x 13&#8243;<\/p><p>LED-Beleuchtung:Ja, 3-stufig<\/p><p>Bilddrehung:0\u00b0 \/ 180\u00b0<\/p><p>Frequenz:50\/60Hz<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-26bef6e\" data-id=\"26bef6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed730a6 elementor-widget elementor-widget-toggle\" data-id=\"ed730a6\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2481\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2481\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Mikrofon<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2481\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2481\"><p>Eingebautes Mikrophon:Omnidirektional<\/p><p>Mikrofonspezifikationen: Empfindlichkeit S 94 dB SPL bei 1 kHz, min. 29 dB, Tye 26, max. 23 dBFS<\/p><p>Besonderheit:<br \/>Ger\u00e4uschunterdr\u00fcckung<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c0afa66\" data-id=\"c0afa66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3b8d66 elementor-widget elementor-widget-toggle\" data-id=\"b3b8d66\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1881\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1881\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Andere<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1881\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1881\"><p>Konnektivit\u00e4t:USB-C auf Typ-A 2.0<\/p><p>Angetrieben von:USB 2.0 5V\/500mA<\/p><p>Protokoll:UVC; UAC; Plug-and-Play<\/p><p>Betriebssystem:<br \/>Fenster 11, 10<br \/>MacOS 10.10 oder h\u00f6her<br \/>Chrome OS<\/p><p>Kabel:USB-C auf Typ-A 1,5 m\/ 4,9 Fu\u00df<\/p><p>Produktabmessungen:197x51x20mm \/ 7,7\u2033x2\u2033x0,8\u2033<\/p><p>Nettogewicht:450 g \/ 15,8 oz<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e701ea elementor-widget elementor-widget-spacer\" data-id=\"7e701ea\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f87ea3a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"f87ea3a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8703007\" data-id=\"8703007\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-862eab4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"862eab4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f7c26da\" data-id=\"f7c26da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5dd8545\" data-id=\"5dd8545\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac92400 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ac92400\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjE0OTIsInRvZ2dsZSI6ZmFsc2V9\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Ein Partner werden<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bba8949\" data-id=\"bba8949\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dokumentenkamera 4K-Doc-Cam\/Webcam mit Mikrofon mit Ger\u00e4uschunterdr\u00fcckung Datenblatt Ideao VisualCam (Windows\/Mac) IdeaoCam (Chrome-Erweiterung) Ideao VisualCam Lite (Android) 13-MP-Kamera Mikrofon mit Ger\u00e4uschunterdr\u00fcckung Intelligenter Fokus G-Sensor automatisch drehen LED-Licht Plug &#038; Play Kompaktes Design Interaktive Software Perfektes Detail. Perfekte Fernkommunikation. Pr\u00e4sentieren und unterrichten Sie wie ein Profi mit der vielseitigen 4K-Dokumentenkamera Innex DC500. Es ist ein ultimatives Werkzeug [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":49224,"parent":52094,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-52142","page","type-page","status-publish","has-post-thumbnail","hentry","entry","has-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Innex DC500 4K Dokumentenkamera- FunTech Innovation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Innex DC500 4K Dokumentenkamera- FunTech Innovation\" \/>\n<meta property=\"og:description\" content=\"Dokumentenkamera 4K-Doc-Cam\/Webcam mit Mikrofon mit Ger\u00e4uschunterdr\u00fcckung Datenblatt Ideao VisualCam (Windows\/Mac) IdeaoCam (Chrome-Erweiterung) Ideao VisualCam Lite (Android) 13-MP-Kamera Mikrofon mit Ger\u00e4uschunterdr\u00fcckung Intelligenter Fokus G-Sensor automatisch drehen LED-Licht Plug &#038; Play Kompaktes Design Interaktive Software Perfektes Detail. Perfekte Fernkommunikation. Pr\u00e4sentieren und unterrichten Sie wie ein Profi mit der vielseitigen 4K-Dokumentenkamera Innex DC500. Es ist ein ultimatives Werkzeug [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/\" \/>\n<meta property=\"og:site_name\" content=\"FunTech Innovation\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T07:18:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/same-size-dc500.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/\",\"url\":\"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/\",\"name\":\"Innex DC500 4K Dokumentenkamera- FunTech Innovation\",\"isPartOf\":{\"@id\":\"https:\/\/funtechinnovation.com\/#website\"},\"datePublished\":\"2023-02-28T19:34:23+00:00\",\"dateModified\":\"2026-01-13T07:18:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/funtechinnovation.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Innex\",\"item\":\"https:\/\/funtechinnovation.com\/innex\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Innex Visualizer DC500\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/funtechinnovation.com\/#website\",\"url\":\"https:\/\/funtechinnovation.com\/\",\"name\":\"FunTech Innovation\",\"description\":\"MEET THE FUTURE\",\"publisher\":{\"@id\":\"https:\/\/funtechinnovation.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/funtechinnovation.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/funtechinnovation.com\/#organization\",\"name\":\"FunTech Innovation\",\"url\":\"https:\/\/funtechinnovation.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/funtechinnovation.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/08\/website-master-logo-white.png\",\"contentUrl\":\"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/08\/website-master-logo-white.png\",\"width\":461,\"height\":159,\"caption\":\"FunTech Innovation\"},\"image\":{\"@id\":\"https:\/\/funtechinnovation.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Innex DC500 4K Dokumentenkamera- FunTech Innovation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/","og_locale":"de_DE","og_type":"article","og_title":"Innex DC500 4K Dokumentenkamera- FunTech Innovation","og_description":"Dokumentenkamera 4K-Doc-Cam\/Webcam mit Mikrofon mit Ger\u00e4uschunterdr\u00fcckung Datenblatt Ideao VisualCam (Windows\/Mac) IdeaoCam (Chrome-Erweiterung) Ideao VisualCam Lite (Android) 13-MP-Kamera Mikrofon mit Ger\u00e4uschunterdr\u00fcckung Intelligenter Fokus G-Sensor automatisch drehen LED-Licht Plug &#038; Play Kompaktes Design Interaktive Software Perfektes Detail. Perfekte Fernkommunikation. Pr\u00e4sentieren und unterrichten Sie wie ein Profi mit der vielseitigen 4K-Dokumentenkamera Innex DC500. Es ist ein ultimatives Werkzeug [&hellip;]","og_url":"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/","og_site_name":"FunTech Innovation","article_modified_time":"2026-01-13T07:18:39+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2023\/05\/same-size-dc500.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/","url":"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/","name":"Innex DC500 4K Dokumentenkamera- FunTech Innovation","isPartOf":{"@id":"https:\/\/funtechinnovation.com\/#website"},"datePublished":"2023-02-28T19:34:23+00:00","dateModified":"2026-01-13T07:18:39+00:00","breadcrumb":{"@id":"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/funtechinnovation.com\/de\/innex\/visualizer-dc500\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/funtechinnovation.com\/"},{"@type":"ListItem","position":2,"name":"Innex","item":"https:\/\/funtechinnovation.com\/innex\/"},{"@type":"ListItem","position":3,"name":"Innex Visualizer DC500"}]},{"@type":"WebSite","@id":"https:\/\/funtechinnovation.com\/#website","url":"https:\/\/funtechinnovation.com\/","name":"FunTech Innovation","description":"MEET THE FUTURE","publisher":{"@id":"https:\/\/funtechinnovation.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/funtechinnovation.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/funtechinnovation.com\/#organization","name":"FunTech Innovation","url":"https:\/\/funtechinnovation.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/funtechinnovation.com\/#\/schema\/logo\/image\/","url":"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/08\/website-master-logo-white.png","contentUrl":"https:\/\/funtechinnovation.com\/wp-content\/uploads\/2022\/08\/website-master-logo-white.png","width":461,"height":159,"caption":"FunTech Innovation"},"image":{"@id":"https:\/\/funtechinnovation.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/pages\/52142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/comments?post=52142"}],"version-history":[{"count":14,"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/pages\/52142\/revisions"}],"predecessor-version":[{"id":92338,"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/pages\/52142\/revisions\/92338"}],"up":[{"embeddable":true,"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/pages\/52094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/media\/49224"}],"wp:attachment":[{"href":"https:\/\/funtechinnovation.com\/de\/wp-json\/wp\/v2\/media?parent=52142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}